{"id":8034,"date":"2020-03-27T17:51:00","date_gmt":"2020-03-27T20:51:00","guid":{"rendered":"https:\/\/arquivosfutebolbrasil.com.br\/blog\/?p=8034"},"modified":"2020-03-18T17:55:44","modified_gmt":"2020-03-18T20:55:44","slug":"torneio-inicio-brasiliense-1962","status":"publish","type":"post","link":"https:\/\/arquivosfutebolbrasil.com.br\/blog\/2020\/03\/27\/torneio-inicio-brasiliense-1962\/","title":{"rendered":"Torneio In\u00edcio Brasiliense &#8211; 1962"},"content":{"rendered":"\n<p>Data: 10 de junho de 1962<br>Local: Est\u00e1dio Ciro Machado do Esp\u00edrito Santo<\/p>\n\n\n\n<p>1\u00ba jogo &#8211; Defel\u00ea 0x0 Colombo (3&#215;1 pen)<br>2\u00ba jogo &#8211; Rabello 3&#215;0 Cruzeiro do Sul<br>3\u00ba jogo &#8211; Guanabara 0x0 Nacional (3&#215;1 pen)<br>4\u00ba jogo &#8211; Alvorada 1&#215;0 Presid\u00eancia<br>5\u00ba jogo &#8211; Gr\u00eamio 1&#215;0 Guar\u00e1<br>6\u00ba jogo &#8211; Defel\u00ea W0x0 Planalto<br>7\u00ba jogo &#8211; Guanabara 0x0 Rabello (2&#215;1 pen)<br>8\u00ba jogo &#8211; Alvorada 0x0 Gr\u00eamio (2&#215;1 pen)<br>Final \u2013 Gunabara 2&#215;2 Alvorada (6&#215;5 pen)<\/p>\n\n\n\n<p>Campe\u00e3 \u2013 Associa\u00e7\u00e3o Atl\u00e9tica\nGuanabara (Bras\u00edlia \u2013 DF)<\/p>\n\n\n\n<p>Fonte: Jos\u00e9 Ricardo Caldas e\nAlmeida<\/p>\n\r\n","protected":false},"excerpt":{"rendered":"<p>Data: 10 de junho de 1962Local: Est\u00e1dio Ciro Machado do Esp\u00edrito Santo 1\u00ba jogo &#8211; Defel\u00ea 0x0 Colombo (3&#215;1 pen)2\u00ba jogo &#8211; Rabello 3&#215;0 Cruzeiro do Sul3\u00ba jogo &#8211; Guanabara 0x0 Nacional (3&#215;1 pen)4\u00ba jogo &#8211; Alvorada 1&#215;0 Presid\u00eancia5\u00ba jogo &#8211; Gr\u00eamio 1&#215;0 Guar\u00e16\u00ba jogo &#8211; Defel\u00ea W0x0 Planalto7\u00ba jogo &#8211; Guanabara 0x0 Rabello (2&#215;1 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48,17],"tags":[],"class_list":["post-8034","post","type-post","status-publish","format-standard","hentry","category-campeonatos-historicos","category-distrito-federal-brasilia"],"_links":{"self":[{"href":"https:\/\/arquivosfutebolbrasil.com.br\/blog\/wp-json\/wp\/v2\/posts\/8034"}],"collection":[{"href":"https:\/\/arquivosfutebolbrasil.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/arquivosfutebolbrasil.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/arquivosfutebolbrasil.com.br\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/arquivosfutebolbrasil.com.br\/blog\/wp-json\/wp\/v2\/comments?post=8034"}],"version-history":[{"count":1,"href":"https:\/\/arquivosfutebolbrasil.com.br\/blog\/wp-json\/wp\/v2\/posts\/8034\/revisions"}],"predecessor-version":[{"id":8035,"href":"https:\/\/arquivosfutebolbrasil.com.br\/blog\/wp-json\/wp\/v2\/posts\/8034\/revisions\/8035"}],"wp:attachment":[{"href":"https:\/\/arquivosfutebolbrasil.com.br\/blog\/wp-json\/wp\/v2\/media?parent=8034"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/arquivosfutebolbrasil.com.br\/blog\/wp-json\/wp\/v2\/categories?post=8034"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/arquivosfutebolbrasil.com.br\/blog\/wp-json\/wp\/v2\/tags?post=8034"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}