{"id":30477,"date":"2024-05-18T22:05:49","date_gmt":"2024-05-19T01:05:49","guid":{"rendered":"https:\/\/arquivosfutebolbrasil.com.br\/blog\/?p=30477"},"modified":"2024-05-18T22:05:50","modified_gmt":"2024-05-19T01:05:50","slug":"campeonato-carioca-feminino-2010","status":"publish","type":"post","link":"https:\/\/arquivosfutebolbrasil.com.br\/blog\/2024\/05\/18\/campeonato-carioca-feminino-2010\/","title":{"rendered":"Campeonato Carioca &#8211; Feminino &#8211; 2010"},"content":{"rendered":"\n<p><strong>Equipes Participantes:<\/strong><\/p>\n\n\n\n<p>Clube de Regatas Vasco da Gama (Rio de Janeiro &#8211; RJ)<br>Clube dos Empregados da Petrobras (Duque de Caxias &#8211; RJ)<br>Volta Redonda Futebol Clube (Volta Redonda &#8211; RJ)<\/p>\n\n\n\n<p><strong>1\u00ba Turno<\/strong><\/p>\n\n\n\n<p>29.08.2010<br>Vasco da Gama 2&#215;1 CEPE, em Duque de Caxias<br>05.09.2010<br>CEPE 2&#215;0 Volta Redonda, em Volta Redonda<br>08.09.2010<br>Vasco da Gama 3&#215;0 Volta Redonda, no Rio de Janeiro<\/p>\n\n\n\n<p><strong>2\u00ba Turno<\/strong><\/p>\n\n\n\n<p>11.09.2010<br>CEPE 3&#215;0 Vasco da Gama, no Rio de Janeiro<br>19.09.2010<br>Volta Redonda 2&#215;1 CEPE, em Duque de Caxias<br>25.09.2010<br>Volta Redonda 1&#215;1 Vasco da Gama, em Volta Redonda<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"173\" height=\"198\" src=\"https:\/\/arquivosfutebolbrasil.com.br\/blog\/wp-content\/uploads\/2024\/05\/image-55.png\" alt=\"\" class=\"wp-image-30478\" style=\"width:121px;height:auto\"\/><\/figure><\/div>\n\n\n<p>Campe\u00e3o &#8211; Clube de Regatas Vasco da Gama (Rio de Janeiro &#8211; RJ)<\/p>\n\n\n\n<p>Fonte: Julio Bovi Diogo<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Equipes Participantes: Clube de Regatas Vasco da Gama (Rio de Janeiro &#8211; RJ)Clube dos Empregados da Petrobras (Duque de Caxias &#8211; RJ)Volta Redonda Futebol Clube (Volta Redonda &#8211; RJ) 1\u00ba Turno 29.08.2010Vasco da Gama 2&#215;1 CEPE, em Duque de Caxias05.09.2010CEPE 2&#215;0 Volta Redonda, em Volta Redonda08.09.2010Vasco da Gama 3&#215;0 Volta Redonda, no Rio de Janeiro [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48,50,47,29],"tags":[],"class_list":["post-30477","post","type-post","status-publish","format-standard","hentry","category-campeonatos-historicos","category-futebol-feminino","category-jogos-historicos","category-rio-de-janeiro"],"_links":{"self":[{"href":"https:\/\/arquivosfutebolbrasil.com.br\/blog\/wp-json\/wp\/v2\/posts\/30477"}],"collection":[{"href":"https:\/\/arquivosfutebolbrasil.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/arquivosfutebolbrasil.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/arquivosfutebolbrasil.com.br\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/arquivosfutebolbrasil.com.br\/blog\/wp-json\/wp\/v2\/comments?post=30477"}],"version-history":[{"count":1,"href":"https:\/\/arquivosfutebolbrasil.com.br\/blog\/wp-json\/wp\/v2\/posts\/30477\/revisions"}],"predecessor-version":[{"id":30479,"href":"https:\/\/arquivosfutebolbrasil.com.br\/blog\/wp-json\/wp\/v2\/posts\/30477\/revisions\/30479"}],"wp:attachment":[{"href":"https:\/\/arquivosfutebolbrasil.com.br\/blog\/wp-json\/wp\/v2\/media?parent=30477"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/arquivosfutebolbrasil.com.br\/blog\/wp-json\/wp\/v2\/categories?post=30477"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/arquivosfutebolbrasil.com.br\/blog\/wp-json\/wp\/v2\/tags?post=30477"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}