{"id":2359,"date":"2019-11-25T08:26:06","date_gmt":"2019-11-25T11:26:06","guid":{"rendered":"https:\/\/arquivosfutebolbrasil.com.br\/blog\/?p=2359"},"modified":"2019-11-23T22:26:36","modified_gmt":"2019-11-24T01:26:36","slug":"torneio-inicio-alagoano-1933","status":"publish","type":"post","link":"https:\/\/arquivosfutebolbrasil.com.br\/blog\/2019\/11\/25\/torneio-inicio-alagoano-1933\/","title":{"rendered":"Torneio In\u00edcio Alagoano &#8211; 1933"},"content":{"rendered":"\n<p>Data: 06 de Agosto de 1933<br>\nLocal: Macei\u00f3 &#8211; AL<\/p>\n\n\n\n<p>1\u00ba Jogo &#8211; C.S.A. 2&#215;0 Vasco da Gama<br>\n2\u00ba Jogo &#8211; Uruguai 1&#215;0 Barroso<br>\n3\u00ba Jogo &#8211; Nordeste 0x0 Duque de Caxias (1-0 esc)<br>\n4\u00ba Jogo &#8211; C.S.A. 1&#215;0 Uruguai<br>\nFinal &#8211; C.S.A. 0x0 Nordeste (2&#215;0 esc)<\/p>\n\n\n\n<p>Campe\u00e3o &#8211; Centro Sportivo Alagoano (Macei\u00f3 &#8211; AL)<\/p>\n\n\n\n<p>Fonte: Livro &#8220;Futebol Alagoano Atrav\u00e9s Dos Tempos&#8221;<\/p>\n\r\n","protected":false},"excerpt":{"rendered":"<p>Data: 06 de Agosto de 1933 Local: Macei\u00f3 &#8211; AL 1\u00ba Jogo &#8211; C.S.A. 2&#215;0 Vasco da Gama 2\u00ba Jogo &#8211; Uruguai 1&#215;0 Barroso 3\u00ba Jogo &#8211; Nordeste 0x0 Duque de Caxias (1-0 esc) 4\u00ba Jogo &#8211; C.S.A. 1&#215;0 Uruguai Final &#8211; C.S.A. 0x0 Nordeste (2&#215;0 esc) Campe\u00e3o &#8211; Centro Sportivo Alagoano (Macei\u00f3 &#8211; AL) [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,48],"tags":[],"class_list":["post-2359","post","type-post","status-publish","format-standard","hentry","category-alagoas","category-campeonatos-historicos"],"_links":{"self":[{"href":"https:\/\/arquivosfutebolbrasil.com.br\/blog\/wp-json\/wp\/v2\/posts\/2359"}],"collection":[{"href":"https:\/\/arquivosfutebolbrasil.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/arquivosfutebolbrasil.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/arquivosfutebolbrasil.com.br\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/arquivosfutebolbrasil.com.br\/blog\/wp-json\/wp\/v2\/comments?post=2359"}],"version-history":[{"count":1,"href":"https:\/\/arquivosfutebolbrasil.com.br\/blog\/wp-json\/wp\/v2\/posts\/2359\/revisions"}],"predecessor-version":[{"id":2360,"href":"https:\/\/arquivosfutebolbrasil.com.br\/blog\/wp-json\/wp\/v2\/posts\/2359\/revisions\/2360"}],"wp:attachment":[{"href":"https:\/\/arquivosfutebolbrasil.com.br\/blog\/wp-json\/wp\/v2\/media?parent=2359"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/arquivosfutebolbrasil.com.br\/blog\/wp-json\/wp\/v2\/categories?post=2359"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/arquivosfutebolbrasil.com.br\/blog\/wp-json\/wp\/v2\/tags?post=2359"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}