{"id":12039,"date":"2020-05-19T06:29:07","date_gmt":"2020-05-19T09:29:07","guid":{"rendered":"https:\/\/arquivosfutebolbrasil.com.br\/blog\/?p=12039"},"modified":"2020-05-19T06:29:08","modified_gmt":"2020-05-19T09:29:08","slug":"festival-beneficente-carioca-1923","status":"publish","type":"post","link":"https:\/\/arquivosfutebolbrasil.com.br\/blog\/2020\/05\/19\/festival-beneficente-carioca-1923\/","title":{"rendered":"Festival Beneficente Carioca \u2013 1923"},"content":{"rendered":"\n<p>Data: 18 de Mar\u00e7o de 1923<br>Local: Campo do Andarahy, no Rio de Janeiro \u2013 RJ<\/p>\n\n\n\n<p>1\u00ba Quadros &#8211; Modesto (Rio de Janeiro) 2&#215;1 Ypiranga (Rio de Janeiro)<br>1\u00ba Quadros &#8211; Vila Isabel (Rio de Janeiro) 1&#215;1 Mangueira (Rio de Janeiro)<br>1\u00ba Quadros &#8211; Andarahy (Rio de Janeiro) 3&#215;1 Vasco da Gama<\/p>\n\n\n\n<p>Fonte: A Noite<\/p>\n\r\n","protected":false},"excerpt":{"rendered":"<p>Data: 18 de Mar\u00e7o de 1923Local: Campo do Andarahy, no Rio de Janeiro \u2013 RJ 1\u00ba Quadros &#8211; Modesto (Rio de Janeiro) 2&#215;1 Ypiranga (Rio de Janeiro)1\u00ba Quadros &#8211; Vila Isabel (Rio de Janeiro) 1&#215;1 Mangueira (Rio de Janeiro)1\u00ba Quadros &#8211; Andarahy (Rio de Janeiro) 3&#215;1 Vasco da Gama Fonte: A Noite<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[46,47,29],"tags":[],"class_list":["post-12039","post","type-post","status-publish","format-standard","hentry","category-jogos-amistosos-nacionais","category-jogos-historicos","category-rio-de-janeiro"],"_links":{"self":[{"href":"https:\/\/arquivosfutebolbrasil.com.br\/blog\/wp-json\/wp\/v2\/posts\/12039"}],"collection":[{"href":"https:\/\/arquivosfutebolbrasil.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/arquivosfutebolbrasil.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/arquivosfutebolbrasil.com.br\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/arquivosfutebolbrasil.com.br\/blog\/wp-json\/wp\/v2\/comments?post=12039"}],"version-history":[{"count":1,"href":"https:\/\/arquivosfutebolbrasil.com.br\/blog\/wp-json\/wp\/v2\/posts\/12039\/revisions"}],"predecessor-version":[{"id":12040,"href":"https:\/\/arquivosfutebolbrasil.com.br\/blog\/wp-json\/wp\/v2\/posts\/12039\/revisions\/12040"}],"wp:attachment":[{"href":"https:\/\/arquivosfutebolbrasil.com.br\/blog\/wp-json\/wp\/v2\/media?parent=12039"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/arquivosfutebolbrasil.com.br\/blog\/wp-json\/wp\/v2\/categories?post=12039"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/arquivosfutebolbrasil.com.br\/blog\/wp-json\/wp\/v2\/tags?post=12039"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}